{"id":9491,"date":"2017-05-18T15:55:57","date_gmt":"2017-05-18T13:55:57","guid":{"rendered":"http:\/\/blog.nastribrizzolari.com\/?p=9491\/"},"modified":"2017-05-23T13:32:54","modified_gmt":"2017-05-23T11:32:54","slug":"emoticonos-envoltorios-jovenes","status":"publish","type":"post","link":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/","title":{"rendered":"Emoticonos para envoltorios j\u00f3venes"},"content":{"rendered":"<h2>El papel de regalo con emoticonos: ideal para regalos j\u00f3venes<\/h2>\n<p>Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos en atractivos y divertidos. El dise\u00f1o es muy variado, con muchas caras diferentes, personalizadas y expresivas, que llenan el fondo blanco quedando bien separadas, para que los emoticonos brillen y destaquen al m\u00e1ximo. <!--more-->Eligiendo un papel con emoticonos dispondremos de un papel con mil usos. Es bonito, juvenil, lleno de color y extremadamente vers\u00e1til, se puede utilizar no solo como papel, sino tambi\u00e9n como soporte de partida para muchas ideas creativas que podremos realizar en casa, haciendo que participen tambi\u00e9n los m\u00e1s peque\u00f1os (\u00a1pronto veremos c\u00f3mo!). El papel con emoticonos combina a la perfecci\u00f3n con muchos tipos de cintas; aqu\u00ed propondremos la pr\u00e1ctica y din\u00e1mica cinta de rafia, que permite aprovechar al m\u00e1ximo un papel tan variopinto.<\/p>\n<h2>\u00a1Combine su papel, cree su lazo y deje volar su creatividad!<\/h2>\n<p>El <a href=\"http:\/\/www.sadoch.it\/\" target=\"_blank\" rel=\"nofollow\">papel con emoticonos<\/a> est\u00e1 lleno de color y es f\u00e1cil de combinar con una cinta alegre, como la desmelenada <a href=\"\/nastri\/rafia-sintetica\/\">cinta de rafia<\/a>, para crear un efecto juvenil y fuera de los esquemas. Las cintas de rafia pueden combinarse con el fondo neutro o con cualquiera de los colores de las caritas, \u00a1para no frenar su imaginaci\u00f3n! Si se elige la cinta, se puede optar tambi\u00e9n por las versiones metalizadas, todav\u00eda m\u00e1s especiales y exclusivas. Elija la cinta, d\u00e9jese inspirar por nuestra galer\u00eda, cree un lazo extravagante, futurista, minimalista \u00a1y listo! Gracias a la distribuci\u00f3n bien separada de los emoticonos, las caras son muy f\u00e1ciles de recortar, tambi\u00e9n por los m\u00e1s peque\u00f1os, y pueden utilizarse individualmente para combinarlas con el lazo y hacer que el envoltorio sea todav\u00eda m\u00e1s expresivo. Caras sonrientes, p\u00edcaras, sorprendidas, muertas de fr\u00edo, emoticonos que comen helado o escuchan m\u00fasica&#8230; son tantas las expresiones, que siempre encontraremos la ideal para hacer que el lazo sea tambi\u00e9n muy especial. Adem\u00e1s, las caras se pueden poner fuera de contexto y utilizarse para cerrar las cartas y los sobres de las tarjetas, para pegarse en los libros, cuadernos y postales, en el diario, en la nevera o en un im\u00e1n, para levantarnos de buen humor cada ma\u00f1ana. Se puede  recortar un emoticono para pegarlo en una cinta de rafia y crear as\u00ed bigotes, barba y pelo. El papel con emoticonos combinado con la rafia es tan vers\u00e1til que con un simple folio de papel de regalo y un rollo de rafia es como si tuvi\u00e9ramos un kit multiusos para todas las ocasiones.<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-9491 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"Pacchettino Emoticons\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"900\"href='https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-9517\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-9517'>\n\t\t\t\t\tPacchettino Emoticons\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"Nastri pacchetto emoticons\" data-dt-img-description=\"\" data-large_image_width=\"2011\" data-large_image_height=\"2024\"href='https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-9515\" srcset=\"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons-150x150.jpg 150w, https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons-298x300.jpg 298w, https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons-768x773.jpg 768w, https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons-1017x1024.jpg 1017w, https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/nastro-pacchetto-emoticons.jpg 2011w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-9515'>\n\t\t\t\t\tNastri pacchetto emoticons\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"Nastri pacchetto emoticons\" data-dt-img-description=\"\" data-large_image_width=\"1404\" data-large_image_height=\"1112\"href='https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/colori-nastri-pacchetto-emoticons.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/colori-nastri-pacchetto-emoticons-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-9514\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-9514'>\n\t\t\t\t\tNastri pacchetto emoticons\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos en atractivos y divertidos. El dise\u00f1o es muy variado, con muchas caras diferentes, personalizadas y expresivas, que llenan el fondo blanco quedando bien separadas, para que los emoticonos brillen y destaquen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":9516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[199],"tags":[],"class_list":["post-9491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","category-199","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari<\/title>\n<meta name=\"description\" content=\"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari\" \/>\n<meta property=\"og:description\" content=\"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Nastri Brizzolari\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-18T13:55:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-23T11:32:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1793\" \/>\n\t<meta property=\"og:image:height\" content=\"2189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nastri Brizzolari\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nastri Brizzolari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/\"},\"author\":{\"name\":\"Nastri Brizzolari\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/#\\\/schema\\\/person\\\/58326f4ceac76e7c3e465d122619453b\"},\"headline\":\"Emoticonos para envoltorios j\u00f3venes\",\"datePublished\":\"2017-05-18T13:55:57+00:00\",\"dateModified\":\"2017-05-23T11:32:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/\"},\"wordCount\":461,\"image\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/pacco-emoticons-3-piani.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/\",\"url\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/\",\"name\":\"Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/pacco-emoticons-3-piani.jpg\",\"datePublished\":\"2017-05-18T13:55:57+00:00\",\"dateModified\":\"2017-05-23T11:32:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/#\\\/schema\\\/person\\\/58326f4ceac76e7c3e465d122619453b\"},\"description\":\"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/pacco-emoticons-3-piani.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/pacco-emoticons-3-piani.jpg\",\"width\":1793,\"height\":2189,\"caption\":\"Pacchettino Emoticons su 3 piani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/emoticonos-envoltorios-jovenes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/sin-categorizar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Emoticonos para envoltorios j\u00f3venes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/\",\"name\":\"Nastri Brizzolari\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.nastribrizzolari.com\\\/es\\\/#\\\/schema\\\/person\\\/58326f4ceac76e7c3e465d122619453b\",\"name\":\"Nastri Brizzolari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g\",\"caption\":\"Nastri Brizzolari\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari","description":"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/","og_locale":"es_ES","og_type":"article","og_title":"Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari","og_description":"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos","og_url":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/","og_site_name":"Nastri Brizzolari","article_published_time":"2017-05-18T13:55:57+00:00","article_modified_time":"2017-05-23T11:32:54+00:00","og_image":[{"width":1793,"height":2189,"url":"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg","type":"image\/jpeg"}],"author":"Nastri Brizzolari","twitter_misc":{"Escrito por":"Nastri Brizzolari","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#article","isPartOf":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/"},"author":{"name":"Nastri Brizzolari","@id":"https:\/\/blog.nastribrizzolari.com\/es\/#\/schema\/person\/58326f4ceac76e7c3e465d122619453b"},"headline":"Emoticonos para envoltorios j\u00f3venes","datePublished":"2017-05-18T13:55:57+00:00","dateModified":"2017-05-23T11:32:54+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/"},"wordCount":461,"image":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/","url":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/","name":"Emoticonos para envoltorios j\u00f3venes - Nastri Brizzolari","isPartOf":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#primaryimage"},"image":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg","datePublished":"2017-05-18T13:55:57+00:00","dateModified":"2017-05-23T11:32:54+00:00","author":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/#\/schema\/person\/58326f4ceac76e7c3e465d122619453b"},"description":"El papel de regalo con emoticonos: ideal para regalos j\u00f3venes Lleno de color y divertido, este papel es ideal para envolver los regalos transform\u00e1ndolos","breadcrumb":{"@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#primaryimage","url":"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg","contentUrl":"https:\/\/blog.nastribrizzolari.com\/wp-content\/uploads\/2016\/04\/pacco-emoticons-3-piani.jpg","width":1793,"height":2189,"caption":"Pacchettino Emoticons su 3 piani"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.nastribrizzolari.com\/es\/emoticonos-envoltorios-jovenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.nastribrizzolari.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sin categorizar","item":"https:\/\/blog.nastribrizzolari.com\/es\/sin-categorizar\/"},{"@type":"ListItem","position":3,"name":"Emoticonos para envoltorios j\u00f3venes"}]},{"@type":"WebSite","@id":"https:\/\/blog.nastribrizzolari.com\/es\/#website","url":"https:\/\/blog.nastribrizzolari.com\/es\/","name":"Nastri Brizzolari","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.nastribrizzolari.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.nastribrizzolari.com\/es\/#\/schema\/person\/58326f4ceac76e7c3e465d122619453b","name":"Nastri Brizzolari","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3651028a4f38ec24ff96244eacffbe4e170342010c9b6e015f780133922b76b9?s=96&d=mm&r=g","caption":"Nastri Brizzolari"}}]}},"_links":{"self":[{"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/posts\/9491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/comments?post=9491"}],"version-history":[{"count":0,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/posts\/9491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/media\/9516"}],"wp:attachment":[{"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/media?parent=9491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/categories?post=9491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.nastribrizzolari.com\/es\/wp-json\/wp\/v2\/tags?post=9491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}